{"id":38796,"date":"2022-03-02T10:25:58","date_gmt":"2022-03-02T09:25:58","guid":{"rendered":"https:\/\/www.climatecoating.com\/referenser\/"},"modified":"2022-03-29T18:46:14","modified_gmt":"2022-03-29T16:46:14","slug":"referenser","status":"publish","type":"page","link":"https:\/\/www.climatecoating.com\/sv\/referenser\/","title":{"rendered":"Referenser"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; background_animation=&#8221;none&#8221; padding_top=&#8221;14&#8243; padding_bottom=&#8221;100&#8243; css_animation=&#8221;&#8221;][vc_column][vc_column_text]<\/p>\n<h1>Referenser<\/h1>\n<p>[\/vc_column_text]<div class='projects_holder_outer v3 portfolio_with_space portfolio_with_hover_text  qode-filter-position-left'>\n\t<div class='filter_outer left_align'>\n    <div class='filter_holder  without_separator'>\n        <ul>\n            \n                            <li class='filter' data-filter='all'><span>Alla<\/span><\/li>\n            \n                            <li class='filter' data-filter='portfolio_category_2352'><span>Tr\u00e4<\/span>\n                                <\/li>\n                            <li class='filter' data-filter='portfolio_category_2450'><span>Tak<\/span>\n                                <\/li>\n                            <li class='filter' data-filter='portfolio_category_4391'><span>Fasader<\/span>\n                                <\/li>\n                            <li class='filter' data-filter='portfolio_category_4397'><span>Interi\u00f6rer<\/span>\n                                <\/li>\n                            <li class='filter' data-filter='portfolio_category_2261'><span>Monument<\/span>\n                                <\/li>\n                    <\/ul>\n    <\/div>\n<\/div>\n    \t<div class='projects_holder clearfix v3 hover_text portfolio_default_image'>\n\t\t<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Fassadenreinigung-in-Den-Haag_02-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Fasadreng\u00f6ring i Haag 02\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Fassadenreinigung-in-Den-Haag_02-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Fassadenreinigung-in-Den-Haag_02-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Fassadenreinigung-in-Den-Haag_02-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/fasadrengoring-i-haag\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Fasadreng\u00f6ring i Haag<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Wohnbloecke-in-Botkyrka_09-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Flerfamiljshus i Botkyrka 09\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Wohnbloecke-in-Botkyrka_09-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Wohnbloecke-in-Botkyrka_09-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Wohnbloecke-in-Botkyrka_09-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/flerfamiljshus-i-botkyrka\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Flerfamiljshus i Botkyrka<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2014\/06\/referenzen_energiemasterhaus_09-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Referenser energim\u00e4starhus 09\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2014\/06\/referenzen_energiemasterhaus_09-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2014\/06\/referenzen_energiemasterhaus_09-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2014\/06\/referenzen_energiemasterhaus_09-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/energimastarhus\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Energim\u00e4starhus<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Einfamilienhaus-in-Erlenbach_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Frist\u00e5ende hus i Erlenbach 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Einfamilienhaus-in-Erlenbach_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Einfamilienhaus-in-Erlenbach_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Einfamilienhaus-in-Erlenbach_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/fristaende-hus-i-erlenbach\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Frist\u00e5ende hus i Erlenbach<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_2352 portfolio_category_4391 portfolio_category_2261\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Fachwerkhaeuser_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"ClimateCoating \u00ae f\u00f6r korsvirkeshus 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Fachwerkhaeuser_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Fachwerkhaeuser_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Fachwerkhaeuser_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/climatecoating-for-korsvirkeshus\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > ClimateCoating <sup>\u00ae<\/sup> f\u00f6r korsvirkeshus<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_2352\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Renovierungen-mit-Nature_02-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Renoveringar med naturen 02\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Renovierungen-mit-Nature_02-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Renovierungen-mit-Nature_02-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Renovierungen-mit-Nature_02-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/renoveringar-med-naturen\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Renoveringar med naturen<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Mehrfamilienhaus-in-Jonava_03-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Hyreshus i Jonava 03\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Mehrfamilienhaus-in-Jonava_03-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Mehrfamilienhaus-in-Jonava_03-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Mehrfamilienhaus-in-Jonava_03-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/hyreshus-i-jonava\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Hyreshus i Jonava<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_2352\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-weisse-Haus-in-Spremberg_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Vita huset i Spremberg 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-weisse-Haus-in-Spremberg_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-weisse-Haus-in-Spremberg_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-weisse-Haus-in-Spremberg_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/vita-huset-i-spremberg\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Vita huset i Spremberg<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4397 portfolio_category_2261\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Kirche-in-Blokzijl_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Kyrka i Blokzijl 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Kirche-in-Blokzijl_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Kirche-in-Blokzijl_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Kirche-in-Blokzijl_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/kyrka-i-blokzijl\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Kyrka i Blokzijl<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Kindertagesstaette-in-Pankow_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Daghem i Pankow 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Kindertagesstaette-in-Pankow_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Kindertagesstaette-in-Pankow_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Kindertagesstaette-in-Pankow_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/daghem-i-pankow\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Daghem i Pankow<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Reihenhaeuser-in-den-Niederlanden_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Radhus i Nederl\u00e4nderna 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Reihenhaeuser-in-den-Niederlanden_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Reihenhaeuser-in-den-Niederlanden_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Reihenhaeuser-in-den-Niederlanden_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/radhus-i-nederlanderna\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Radhus i Nederl\u00e4nderna<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Kindergarten-in-Vilnius_06-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Dagis i Vilnius 06\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Kindergarten-in-Vilnius_06-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Kindergarten-in-Vilnius_06-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Kindergarten-in-Vilnius_06-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/dagis-i-vilnius\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Dagis i Vilnius<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_2352\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-weisse-Haus-in-Spaarndam_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Vita huset i Spaarndam 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-weisse-Haus-in-Spaarndam_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-weisse-Haus-in-Spaarndam_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-weisse-Haus-in-Spaarndam_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/vita-huset-i-spaarndam\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Vita huset i Spaarndam<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Waschkiesfassade_04-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Tv\u00e4tta grusfasad 04\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Waschkiesfassade_04-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Waschkiesfassade_04-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Waschkiesfassade_04-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/tvatta-grusfasad\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Tv\u00e4tta grusfasad<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4397 portfolio_category_2261\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Kirche-Schermerhorn_13-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Schermerhorn kyrka 13\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Kirche-Schermerhorn_13-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Kirche-Schermerhorn_13-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Kirche-Schermerhorn_13-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/kyrkan-schermerhorn\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Kyrkan Schermerhorn<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Mehrfamilienhaus-in-Kapfenberg_05-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Hyreshus i Kapfenberg 05\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Mehrfamilienhaus-in-Kapfenberg_05-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Mehrfamilienhaus-in-Kapfenberg_05-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Mehrfamilienhaus-in-Kapfenberg_05-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/hyreshus-i-kapfenberg\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Hyreshus i Kapfenberg<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Wohnbloecke-in-Perleberg_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Flerfamiljshus i Perleberg 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Wohnbloecke-in-Perleberg_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Wohnbloecke-in-Perleberg_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Wohnbloecke-in-Perleberg_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/flerfamiljshus-i-perleberg\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Flerfamiljshus i Perleberg<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_2450\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/10\/ThermoActive_Roof_SK_2650x1440px-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"ThermoActive takbel\u00e4ggning\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/10\/ThermoActive_Roof_SK_2650x1440px-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/10\/ThermoActive_Roof_SK_2650x1440px-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/10\/ThermoActive_Roof_SK_2650x1440px-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/schindler-fabrik-i-slovakien\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Schindler fabrik i Slovakien<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_2261\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Stelling-van-Amsterdam_05-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Stelling van Amsterdam 05\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Stelling-van-Amsterdam_05-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Stelling-van-Amsterdam_05-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Stelling-van-Amsterdam_05-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/stelling-van-amsterdam\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Stelling van Amsterdam<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4397\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnhaus-in-Portugal_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Bostadshus i Portugal 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnhaus-in-Portugal_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnhaus-in-Portugal_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnhaus-in-Portugal_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/bostadshus-i-portugal\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Bostadshus i Portugal<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_2352\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Nature-vs-Farben_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Natur vs f\u00e4rger 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Nature-vs-Farben_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Nature-vs-Farben_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Nature-vs-Farben_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/natur-vs-farger\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Natur vs f\u00e4rger<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-Schwarze-Haus-in-Madrid_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Svarta huset i Madrid 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-Schwarze-Haus-in-Madrid_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-Schwarze-Haus-in-Madrid_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-Schwarze-Haus-in-Madrid_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/svarta-huset-i-madrid\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Svarta huset i Madrid<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Dreifamilienhaus-in-Zeuthen_02-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Trefamiljshus i Zeuthen 02\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Dreifamilienhaus-in-Zeuthen_02-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Dreifamilienhaus-in-Zeuthen_02-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Dreifamilienhaus-in-Zeuthen_02-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/trefamiljshus-i-zeuthen\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Trefamiljshus i Zeuthen<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Garagen-in-Forst-nach-7-Jahren_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Garage i Forst efter 7 \u00e5r 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Garagen-in-Forst-nach-7-Jahren_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Garagen-in-Forst-nach-7-Jahren_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Garagen-in-Forst-nach-7-Jahren_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/garage-i-forst-efter-7-ar\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Garage i Forst efter 7 \u00e5r<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Apotheke-in-Witten_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Apotek i Witten 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Apotheke-in-Witten_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Apotheke-in-Witten_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Apotheke-in-Witten_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/apotek-i-witten\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Apotek i Witten<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Die-Waermestrommessung-zu-Rom_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"V\u00e4rmefl\u00f6desm\u00e4tningen f\u00f6r Rom 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Die-Waermestrommessung-zu-Rom_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Die-Waermestrommessung-zu-Rom_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Die-Waermestrommessung-zu-Rom_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/varmeflodesmatningen-i-rom\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > V\u00e4rmefl\u00f6desm\u00e4tningen i Rom<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_2352\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Nature-fuer-Windmuehlen_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Naturen f\u00f6r v\u00e4derkvarnar 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Nature-fuer-Windmuehlen_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Nature-fuer-Windmuehlen_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Nature-fuer-Windmuehlen_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/natur-for-vaderkvarnar\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Natur f\u00f6r v\u00e4derkvarnar<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391 portfolio_category_2352\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-Schwarze-Haus-in-Holland_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Svarta huset i Holland 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-Schwarze-Haus-in-Holland_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-Schwarze-Haus-in-Holland_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Das-Schwarze-Haus-in-Holland_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/svarta-huset-i-holland\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Svarta huset i Holland<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391 portfolio_category_2261\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Verbindungshaus-in-Erlangen_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Broderskapshus i Erlangen 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Verbindungshaus-in-Erlangen_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Verbindungshaus-in-Erlangen_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Verbindungshaus-in-Erlangen_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/brodraskapshus-i-erlangen\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Br\u00f6draskapshus i Erlangen<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnblock-in-Den-Haag_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Flerfamiljshus i Haag 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnblock-in-Den-Haag_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnblock-in-Den-Haag_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnblock-in-Den-Haag_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/flerfamiljshus-i-haag\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Flerfamiljshus i Haag<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Fassaden-nach-x-Jahren_02-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Fasader efter x \u00e5r 02\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Fassaden-nach-x-Jahren_02-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Fassaden-nach-x-Jahren_02-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Fassaden-nach-x-Jahren_02-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/fasader-efter-x-ar\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Fasader efter x \u00e5r<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Sanierung-Bauernhaus-in-den-Niederlanden_07-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Renovering bondg\u00e5rd i Nederl\u00e4nderna 07\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Sanierung-Bauernhaus-in-den-Niederlanden_07-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Sanierung-Bauernhaus-in-den-Niederlanden_07-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Sanierung-Bauernhaus-in-den-Niederlanden_07-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/renovering-bondgard-i-nederlanderna\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Renovering bondg\u00e5rd i Nederl\u00e4nderna<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnhaus-in-Beringe-NL_03-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Bostadshus i Beringe NL 03\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnhaus-in-Beringe-NL_03-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnhaus-in-Beringe-NL_03-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnhaus-in-Beringe-NL_03-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/hus-i-beringe-nl\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Hus i Beringe (NL)<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391 portfolio_category_2261\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Sankt-Petri-Kirche-in-Moenkebude_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"S:t Petri kyrka i M\u00f6nkebude 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Sankt-Petri-Kirche-in-Moenkebude_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Sankt-Petri-Kirche-in-Moenkebude_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2021\/02\/Sankt-Petri-Kirche-in-Moenkebude_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/peterskyrkan-i-monkebude\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Peterskyrkan i M\u00f6nkebude<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnhaus-in-Berlin-nach-6-Jahren_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Bostadshus i Berlin efter 6 \u00e5r 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnhaus-in-Berlin-nach-6-Jahren_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnhaus-in-Berlin-nach-6-Jahren_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Wohnhaus-in-Berlin-nach-6-Jahren_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/bostadshus-i-berlin-efter-6-ar\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Bostadshus i Berlin efter 6 \u00e5r<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_2352\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Holzfassaden-mit-Nature_01-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Tr\u00e4fasader med Nature 01\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Holzfassaden-mit-Nature_01-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Holzfassaden-mit-Nature_01-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Holzfassaden-mit-Nature_01-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/trafasader-med-natur\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Tr\u00e4fasader med natur<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n<article class=\"mix portfolio_category_4391\">\n    <div class='image_holder elegant_hover'>\n        \n<span class='image'><img loading=\"lazy\" decoding=\"async\" width=\"550\" height=\"498\" src=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Mehrfamilienhaus-in-Spremberg_08-550x498.jpg\" class=\"attachment-portfolio-default size-portfolio-default wp-post-image\" alt=\"Hyreshus i Spremberg 08\" srcset=\"https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Mehrfamilienhaus-in-Spremberg_08-550x498.jpg 550w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Mehrfamilienhaus-in-Spremberg_08-480x434.jpg 480w,   https:\/\/www.climatecoating.com\/wp-content\/uploads\/2020\/07\/Mehrfamilienhaus-in-Spremberg_08-125x112.jpg 125w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/span>\n                    <a class='portfolio_link_class' href='https:\/\/www.climatecoating.com\/sv\/referenser\/referens\/hyreshus-i-spremberg\/' target='_self'><\/a>\n\t\t\n        <div class=\"portfolio_shader\"><\/div>\n<div class=\"text_holder\">\n\t<div class=\"text_holder_inner\">\n\t\t<div class=\"text_holder_inner2\">\n\t\t\t<h4 class=\"portfolio_title\" > Hyreshus i Spremberg<\/h4><h6 class=\"portfolio_subtitle\"> <\/h6>\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\t    \n    <\/div>\n<\/article>\n\t\t\t\t\t<div class='filler'><\/div>\n\t\t\t\t\t\t\t\t\t<div class='filler'><\/div>\n\t\t\t\t\t\t\t\t\t<div class='filler'><\/div>\n\t\t\t\t\t<\/div>\n\n    \n\t<\/div>\n[\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row row_type=&#8221;row&#8221; use_row_as_full_screen_section=&#8221;no&#8221; type=&#8221;full_width&#8221; text_align=&#8221;left&#8221; background_animation=&#8221;none&#8221; padding_top=&#8221;14&#8243; padding_bottom=&#8221;100&#8243; css_animation=&#8221;&#8221;][vc_column][vc_column_text] Referenser [\/vc_column_text][\/vc_column][\/vc_row]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":400,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-38796","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.climatecoating.com\/sv\/wp-json\/wp\/v2\/pages\/38796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.climatecoating.com\/sv\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.climatecoating.com\/sv\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.climatecoating.com\/sv\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.climatecoating.com\/sv\/wp-json\/wp\/v2\/comments?post=38796"}],"version-history":[{"count":0,"href":"https:\/\/www.climatecoating.com\/sv\/wp-json\/wp\/v2\/pages\/38796\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.climatecoating.com\/sv\/wp-json\/wp\/v2\/media?parent=38796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}